{"id":604,"date":"2020-12-21T17:32:52","date_gmt":"2020-12-21T17:32:52","guid":{"rendered":"https:\/\/www.seguros-autocaravanas.es\/blog\/?p=604"},"modified":"2024-04-12T17:30:53","modified_gmt":"2024-04-12T17:30:53","slug":"fingian-hacer-turismo-para-distribuir-drogas-con-una-autocaravana","status":"publish","type":"post","link":"https:\/\/www.seguros-autocaravanas.es\/blog\/fingian-hacer-turismo-para-distribuir-drogas-con-una-autocaravana\/12\/2020\/","title":{"rendered":"Fing\u00edan hacer turismo para distribuir drogas con una Autocaravana"},"content":{"rendered":"<p>Dos espa\u00f1oles jubilados <strong>fing\u00edan hacer turismo para distribuir drogas con una autocaravana<\/strong>. La pareja de abuelos aparentemente inofensivos, se desplazaban por toda Espa\u00f1a con grandes cargamentos de hach\u00eds. Ya que la pareja de traficantes de drogas, eran perfectamente camuflados por su avanzada edad.<\/p>\n<p>Los jubilados son habitantes de Pontevedra y cuando regresaban de un viaje de Gibraltar los detuvieron en Oviedo. Al inspeccionar la autocaravana al estacionarse en un \u00e1rea de autocaravanas, les incautaron alrededor de media tonelada de hach\u00eds que transportaban.<\/p>\n<p>La inescrupulosa pareja de jubilados cobra pensi\u00f3n de minusval\u00eda y viven en un chal\u00e9 en Vilanova de Arousa (Pontevedra). La pareja tiene dos hijos, la mujer de 60 a\u00f1os se llama Dolores F. M., quien trabajaba en un geri\u00e1trico, y Antonio N. R., el esposo tiene 61 a\u00f1os y se dedicaba al trabajo de campo. Ambos sin ning\u00fan antecedente delictivo.<\/p>\n<blockquote><p>Utilice siempre el mejor <a href=\"https:\/\/www.seguros-generales.es\/seguros-autocaravanas.html\" target=\"_blank\" rel=\"noopener\">comparador de seguros de autocaravanas<\/a> para encontrar y contratar el mejor seguro disponible en el mercado<\/p><\/blockquote>\n<p>Sin embargo, en Pontevedra, la polic\u00eda les segu\u00eda la pista conjuntamente con el grupo segundo de la Unidad de Drogas y Crimen Organizado (Udyco). Paralelamente realizaban investigaciones de los posibles proveedores, para los cuales la pareja de ancianos ten\u00eda alrededor de 2 a\u00f1os trabajando.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.seguros-autocaravanas.es\/blog\/fingian-hacer-turismo-para-distribuir-drogas-con-una-autocaravana\/12\/2020\/#Atravesaban_la_peninsula_como_distribuidores_de_hachis\" >Atravesaban la pen\u00ednsula como distribuidores de hach\u00eds<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.seguros-autocaravanas.es\/blog\/fingian-hacer-turismo-para-distribuir-drogas-con-una-autocaravana\/12\/2020\/#En_modus_operandi_incluian_una_flotilla_de_coches_con_doble_fondo\" >En modus operandi inclu\u00edan una flotilla de coches con doble fondo<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Atravesaban_la_peninsula_como_distribuidores_de_hachis\"><\/span>Atravesaban la pen\u00ednsula como distribuidores de hach\u00eds<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La pareja viajaba por toda la pen\u00ednsula distribuyendo hach\u00eds. Eran reconocidos por los consumidores en la ruta que traficaban con cierta frecuencia.<\/p>\n<p>El modus operandi iniciaba desde las R\u00edas Baixas y desde all\u00ed se dirig\u00edan a Huelva desplaz\u00e1ndose por Portugal. As\u00ed aparentaban mejor el supuesto viaje de turismo. Segu\u00edan hacia Gibraltar donde la organizaci\u00f3n los esperaba con el encargo, para transportar hacia Espa\u00f1a.<\/p>\n<p>De cada entrega que realizaban les quedaba una cantidad en un rango entre 5 y 10 mil euros. Dependiendo de la cantidad de hach\u00eds que traficaran. Pero este \u00faltimo encargo, sin duda result\u00f3 el m\u00e1s arriesgado y peligroso para los traficantes. Pues en un punto de control de Huela, la Guardia Civil los intercept\u00f3, pero no registraron el veh\u00edculo.<\/p>\n<blockquote><p>Revise ahora los mejores <a href=\"https:\/\/www.seguros-generales.es\/\" target=\"_blank\" rel=\"noopener\">seguros de autocaravanas<\/a> para que haga la mejor elecci\u00f3n del mercado para su autocaravana<\/p><\/blockquote>\n<p>El hach\u00eds deb\u00edan entregarlo en Pa\u00eds vasco y estaba oculto en el <strong>doble fondo de la autocaravana.<\/strong> Los traficantes salieron airosos del punto de control. No obstante, les estaban siguiendo los pasos hasta lograr detenerlos con el cargamento de droga.<\/p>\n<p>Efectivamente, al detenerlos, en un \u00e1rea de estacionamiento de autocaravanas en la autov\u00eda A-8, en Colunga (Asturias), r\u00e1pidamente declararon donde se encontraba la droga. Ocultaban el cargamento en la parte trasera de la autocaravana, que detallado por kilo valdr\u00eda alrededor de 800 mil euros, y distribuido por dosis cerca de los dos millones de \u20ac.<\/p>\n<p>A solicitud del principado de Asturias los encarcelaron de forma provisional, antes de juzgarlos, por reiteraci\u00f3n delictiva y posible riesgo de fuga. De esta manera se rompi\u00f3 la cadena de transporte y distribuci\u00f3n de hach\u00eds en el norte de Espa\u00f1a. Conectada con los narcotraficantes del sur del pa\u00eds y articulado y dirigido desde Galicia.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"En_modus_operandi_incluian_una_flotilla_de_coches_con_doble_fondo\"><\/span>En modus operandi inclu\u00edan una flotilla de coches con doble fondo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La organizaci\u00f3n dispon\u00eda de una flotilla de coches con doble fondo, en los que transportaban los estupefacientes.<\/p>\n<p>En el domicilio de la pareja de delincuentes, se encontr\u00f3 dinero en efectivo en un armario, por la cantidad de 14.000 euros. Adem\u00e1s, se localiz\u00f3 una carabina calibre 22 y 147 cartuchos del mismo calibre y tambi\u00e9n otros 7 cartuchos calibre nueve cortos. Asimismo, se encontraron 5 tel\u00e9fonos m\u00f3viles.<\/p>\n<blockquote><p><strong>Proteja su autocaravana contra robos e incidentes. Adquiera el mejor <\/strong><a href=\"https:\/\/www.seguros-autocaravanas.es\"><strong>seguro de autocaravanas<\/strong><\/a><\/p><\/blockquote>\n<p>Las investigaciones contin\u00faan para desmantelar la red de narcotraficantes. Asimismo, la Unidad de Drogas y Crimen Organizado, rastrea el patrimonio inmobiliario y financiero de la pareja detenida. Tambi\u00e9n est\u00e1n investigando familiares, amigos y allegados de la pareja, por la posibilidad de que est\u00e9n implicados algunos de ellos en la distribuci\u00f3n de las drogas.<\/p>\n<p>Por los momentos, solo han logrado detener a la pareja de jubilados y ambos fueron sentenciados a una condena de entre <strong>tres y seis a\u00f1os en la c\u00e1rcel<\/strong>. En caso de que las investigaciones den como resultado que estuvieron tambi\u00e9n realizando blanqueo de dinero y tenencia de armas, la pena podr\u00eda aumentar para las dos personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos espa\u00f1oles jubilados fing\u00edan hacer turismo para distribuir drogas con una autocaravana. La pareja de abuelos aparentemente inofensivos, se desplazaban por toda Espa\u00f1a con grandes cargamentos de hach\u00eds. Ya que la pareja de traficantes de drogas, eran perfectamente camuflados por su avanzada edad. Los jubilados son habitantes de Pontevedra y cuando regresaban de un viaje [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autocaravanas"],"_links":{"self":[{"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/posts\/604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/comments?post=604"}],"version-history":[{"count":1,"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/posts\/604\/revisions"}],"predecessor-version":[{"id":605,"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/posts\/604\/revisions\/605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/media\/606"}],"wp:attachment":[{"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/media?parent=604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/categories?post=604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seguros-autocaravanas.es\/blog\/wp-json\/wp\/v2\/tags?post=604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}